{"id":10887,"date":"2025-06-25T08:38:39","date_gmt":"2025-06-25T08:38:39","guid":{"rendered":"https:\/\/oftalmedic.rwdesarrollos.es\/catarata-congenita\/"},"modified":"2025-07-02T12:02:55","modified_gmt":"2025-07-02T12:02:55","slug":"catarata-congenita","status":"publish","type":"page","link":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/","title":{"rendered":"Angeborener Grauer Star"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;0&#8243; bottom_padding=&#8220;0&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;specialty_title&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h5 style=\"text-align: left;\">P\u00e4diatrische Ophthalmologie<\/h5>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;submenu_especialidades&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][page_submenu alignment=&#8220;left&#8220; sticky=&#8220;true&#8220; bg_color=&#8220;#c9d6e8&#8243;][page_link link_url=&#8220;\/oftalmologia-pediatrica\/&#8220; title=&#8220;Was ist es&#8220; id=&#8220;1711444925088-7&#8243; tab_id=&#8220;1711444925091-1&#8243;] [\/page_link][page_link title=&#8220;Pathologien&#8220; id=&#8220;1711444925119-9&#8243; link_url=&#8220;\/oftalmologia-pediatrica\/patologias&#8220; tab_id=&#8220;1711444925121-0&#8243;][\/page_link][page_link title=&#8220;H\u00e4ufig gestellte Fragen&#8220; id=&#8220;1711444925157-1&#8243; link_url=&#8220;\/oftalmologia-pediatrica\/faq&#8220; tab_id=&#8220;1711444925158-4&#8243;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;60&#8243; bottom_padding=&#8220;60&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#d0d9e8&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;curve_opacity&#8220;][vc_column column_padding=&#8220;padding-3-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;right&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text el_class=&#8220;blue&#8220;]\n<h5 style=\"text-align: left;\">Was ist es<\/h5>\n<h1 style=\"text-align: left;\">Angeborener Grauer Star<\/h1>\n<p>Der angeborene Graue Star ist eine Katarakt, an der das Kind zum Zeitpunkt der Geburt leidet und die je nach Grad der Tr\u00fcbung der Linse das Sehverm\u00f6gen erschweren oder ernsthaft beeintr\u00e4chtigen kann.<\/p>\n<p>In der Regel ist das Altern die Hauptursache f\u00fcr die Entstehung des Grauen Stars, da die Linse im Laufe der Jahre undurchsichtig wird. Es ist jedoch m\u00f6glich, dass ein Kind diese Pathologie auch bei der Geburt hat. <\/p>\n<p>Im Gegensatz zu Erwachsenen wird diese Art des Grauen Stars nicht durch Ver\u00e4nderungen des Sehverm\u00f6gens diagnostiziert, sondern durch einen sichtbaren wei\u00dflichen oder gr\u00e4ulichen Fleck in der Pupille. Andere Symptome des angeborenen Grauen Stars, die beim Kind als Folge einer Sehschw\u00e4che auftreten k\u00f6nnen, sind die unwillk\u00fcrliche und schnelle Bewegung der Augen (<strong>Nystagmus<\/strong>) oder die Augenabweichung (<strong>Strabismus<\/strong>).[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][toggles style=&#8220;minimal_small&#8220;][toggle color=&#8220;Accent-Color&#8220; heading_tag=&#8220;default&#8220; heading_tag_functionality=&#8220;default&#8220; title=&#8220;Weiterlesen&#8220;][vc_column_text]Wenn es sich um einen leichten angeborenen Katarakt handelt, manifestieren sich diese Symptome m\u00f6glicherweise nicht deutlich genug. Daher ist es wichtig, das Kind nach der Geburt einer ersten augen\u00e4rztlichen Untersuchung zu unterziehen, um sie sowie andere angeborene Sehst\u00f6rungen auszuschlie\u00dfen.<\/p>\n<p>Das Vorhandensein (in einem oder beiden Augen) ist eine seltene Situation, die in der Regel mit erblichen Faktoren verbunden ist, obwohl es auch andere Ursachen geben kann, wie z. B. damit verbundene Augenpathologien oder genetische Erkrankungen.[\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;3405&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;Fade In&#8220; animation_easing=&#8220;default&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;50&#8243; bottom_padding=&#8220;50&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;tratamiento-esp&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#c9d6e8&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;curve_opacity&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h2 style=\"text-align: center;\">Behandlung<\/h2>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;40&#8243;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;padding-3-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#f8f8f8&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1454&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220;][vc_column_text]Zun\u00e4chst ist es wichtig, dass der Augenarzt, der sich auf Katarakte im Kindesalter spezialisiert hat, eine vollst\u00e4ndige Untersuchung beider Augen durchf\u00fchrt, um festzustellen, ob sie eines oder beide betreffen und wie schwer sie sind, sowie um die Ursache zu identifizieren, die sie verursacht.<\/p>\n<p>Wenn der Grad der Kataraktbeteiligung gering ist, besteht die empfohlene Behandlung darin, die sp\u00e4tere Entwicklung streng zu kontrollieren, obwohl eine Rehabilitationsbehandlung auch durchgef\u00fchrt werden kann, wenn sie nur auf einem Auge auftritt.[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=&#8220;padding-3-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#f8f8f8&#8243; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1341&#8243; image_size=&#8220;full&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;center&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][divider line_type=&#8220;No Line&#8220;][vc_column_text]\n<p style=\"text-align: left;\">Wenn der Graue Star die visuelle Entwicklung des Kindes beeintr\u00e4chtigt, muss er so schnell wie m\u00f6glich operativ entfernt werden, um eine gute Prognose f\u00fcr die Wiederherstellung des Sehverm\u00f6gens zu erhalten. Bei der Kataraktoperation bei Kindern wird die Linse entfernt, genau wie bei Erwachsenen. <\/p>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;30&#8243;][nectar_btn size=&#8220;medium&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;\/cataratas\/tratamiento-laser&#8220; text=&#8220;MEHR ANZEIGEN&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;50&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;tratamiento-esp&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#1c2940&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;curve_opacity&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h2 style=\"text-align: center;\">Andere Pathologien<\/h2>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;40&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;60&#8243; bottom_padding=&#8220;10&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;enlaces-patologias&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#ffffff&#8220; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;speech&#8220;][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/catarata-congenita&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">ANGEBORENER GRAUER STAR<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/conjuntivitis&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">BINDEHAUTENTZ\u00dcNDUNG<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/daltonismo&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">FARBENBLINDHEIT<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/defectos-refractivos&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">REFRAKTIVE DEFEKTE<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;10&#8243; bottom_padding=&#8220;160&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; class=&#8220;enlaces-patologias-2&#8243; id=&#8220;enlaces-patologias&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; enable_shape_divider=&#8220;true&#8220; shape_divider_color=&#8220;#1c2940&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;curve_opacity&#8220;][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/estrabismo&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">STRABISMUS<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/glaucoma-congenito&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">ANGEBORENES GLAUKOM<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; boxed=&#8220;true&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/ojo-vago&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">FAULES AUGE<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_color_hover=&#8220;#1c2940&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;small_depth&#8220; column_border_radius=&#8220;3px&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;3px&#8220; column_border_color=&#8220;#1c2940&#8243; column_border_style=&#8220;solid&#8220; column_link=&#8220;\/oftalmologia-pediatrica\/ptosis-palpebral&#8220;][vc_column_text]\n<h5 style=\"text-align: center;\">PTOSIS PALPEBRAL<\/h5>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8220;padding-1-percent&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; centered_text=&#8220;true&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/6&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;top&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#1c2940&#8243; scene_position=&#8220;center&#8220; top_padding=&#8220;60&#8243; bottom_padding=&#8220;60&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;sec_8_home&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; el_class=&#8220;form-light&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text el_class=&#8220;white&#8220;]\n<h3 style=\"text-transform: none; font-weight: 300;\"><strong>ABONNIERE<\/strong><br \/>\nunseren Newsletter<\/h3>\n<p>So erf\u00e4hrst du als Erster alle Neuigkeiten der Gruppe Oftalmedic Salv\u00e0 und erh\u00e4ltst exklusive Angebote, die dich interessieren k\u00f6nnten.[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10072-o1\" lang=\"de-DE\" dir=\"ltr\" data-wpcf7-id=\"10072\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/de\/wp-json\/wp\/v2\/pages\/10887#wpcf7-f10072-o1\" method=\"post\" class=\"wpcf7-form init wpcf7-acceptance-as-validation\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10072\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10072-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"wpcf7-turnstile cf-turnstile\" data-sitekey=\"0x4AAAAAACrqnsGY4NFqb7wN\" data-response-field-name=\"_wpcf7_turnstile_response\"><\/div>\n\n<p><label> E-Mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Name<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<div style=\"display:none!important;\">\n\t<p><!-- Mailchimp for WordPress v4.13.1 - https:\/\/www.mc4wp.com\/ --><input type=\"hidden\" name=\"_mc4wp_subscribe_contact-form-7\" value=\"0\" \/><span class=\"mc4wp-checkbox mc4wp-checkbox-contact-form-7 \"><label><input type=\"checkbox\" name=\"_mc4wp_subscribe_contact-form-7\" value=\"1\" ><span>Quiero recibir comunicaciones personalizadas para estar al d\u00eda de las novedades m\u00e1s relevantes sobre servicios, t\u00e9cnicas o tratamientos m\u00e9dicos y noticias sobre el Grupo Oftalmedic Salv\u00e0 por correo electr\u00f3nico, de acuerdo a la Pol\u00edtica de Privacidad.<\/span><\/label><\/span><!-- \/ Mailchimp for WordPress -->\n\t<\/p>\n<\/div>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ich habe die <a href=\"\/politica-privacidad\/\" target=\"_blank\" style=\"color:#fff!important;\">Datenschutzrichtlinie<\/a> von Oftalmedic Salv\u00e0 gelesen und akzeptiere sie.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p style=\"font-size: 12px!important;\"><span style=\"color: #ffffff;\">GRUNDINFORMATIONEN ZUM DATENSCHUTZ.<\/span><br \/>\n<span style=\"color: #ffffff;\">Der f\u00fcr die Datenverarbeitung Verantwortliche ist die Oftalmedic Salv\u00e0 Gruppe. Wir verarbeiten Ihre personenbezogenen Daten auf Grundlage Ihrer ausdr\u00fccklichen Einwilligung, um Ihnen die von Ihnen in unseren Zentren in Anspruch genommenen medizinischen und pflegerischen Leistungen zu erbringen sowie f\u00fcr die in der Datenschutzrichtlinie definierten weiteren Zwecke. Diese Daten werden nur im gesetzlich vorgeschriebenen Umfang an Dritte weitergegeben. Sie k\u00f6nnen jederzeit Ihre Rechte auf Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Widerspruch und Daten\u00fcbertragbarkeit aus\u00fcben, die in den erg\u00e4nzenden Datenschutzinformationen auf unserer Website (\u201eDatenschutzrichtlinie\u201c) ausf\u00fchrlich beschrieben sind. <\/span>\n<\/p>\n<p>[recaptcha]\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Absenden\" \/>\n<\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;792&#8243; background_image_position=&#8220;center center&#8220; background_image_stacking=&#8220;default&#8220; background_image_loading=&#8220;default&#8220; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; bg_color=&#8220;#ffffff&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;0&#8243; bottom_padding=&#8220;0&#8243; text_color=&#8220;light&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; id=&#8220;specialty_title&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text] P\u00e4diatrische Ophthalmologie [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":11308,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10887","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder<\/title>\n<meta name=\"description\" content=\"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder\" \/>\n<meta property=\"og:description\" content=\"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/\" \/>\n<meta property=\"og:site_name\" content=\"Oftalmedic Salv\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OftalmedicSalva\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T12:02:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OftalmedicSalva\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"19\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/catarata-congenita\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/catarata-congenita\\\/\",\"name\":\"Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#website\"},\"datePublished\":\"2025-06-25T08:38:39+00:00\",\"dateModified\":\"2025-07-02T12:02:55+00:00\",\"description\":\"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/catarata-congenita\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/catarata-congenita\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/catarata-congenita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00e4diatrische Ophthalmologie\",\"item\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/paediatrische-ophthalmologie\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Angeborener Grauer Star\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/\",\"name\":\"Oftalmedic Salv\u00e1\",\"description\":\"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#organization\",\"name\":\"[wpseo_titles]company_Nombre\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"contentUrl\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"width\":200,\"height\":58,\"caption\":\"[wpseo_titles]company_Nombre\"},\"image\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OftalmedicSalva\\\/\",\"https:\\\/\\\/x.com\\\/OftalmedicSalva\",\"https:\\\/\\\/www.instagram.com\\\/oftalmedic_salva\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWrAdUQk6ZmrfVUqBwX0cug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/oftalmedic-clnica-salv\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder","description":"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/","og_locale":"de_DE","og_type":"article","og_title":"Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder","og_description":"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.","og_url":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/","og_site_name":"Oftalmedic Salv\u00e1","article_publisher":"https:\/\/www.facebook.com\/OftalmedicSalva\/","article_modified_time":"2025-07-02T12:02:55+00:00","twitter_card":"summary_large_image","twitter_site":"@OftalmedicSalva","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"19\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/","url":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/","name":"Behandlung des angeborenen Grauen Stars Palm | Augenheilkunde f\u00fcr Kinder","isPartOf":{"@id":"https:\/\/oftalmedic.es\/de\/#website"},"datePublished":"2025-06-25T08:38:39+00:00","dateModified":"2025-07-02T12:02:55+00:00","description":"Behandlung des angeborenen Grauen Stars in Palma. Bei Oftalmedic sind wir Spezialisten f\u00fcr Kinderaugenheilkunde auf Mallorca. Vereinbaren Sie direkt auf unserer Website einen Termin.","breadcrumb":{"@id":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/catarata-congenita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oftalmedic.es\/de\/home\/"},{"@type":"ListItem","position":2,"name":"P\u00e4diatrische Ophthalmologie","item":"https:\/\/oftalmedic.es\/de\/paediatrische-ophthalmologie\/"},{"@type":"ListItem","position":3,"name":"Angeborener Grauer Star"}]},{"@type":"WebSite","@id":"https:\/\/oftalmedic.es\/de\/#website","url":"https:\/\/oftalmedic.es\/de\/","name":"Oftalmedic Salv\u00e1","description":"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.","publisher":{"@id":"https:\/\/oftalmedic.es\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oftalmedic.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/oftalmedic.es\/de\/#organization","name":"[wpseo_titles]company_Nombre","url":"https:\/\/oftalmedic.es\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oftalmedic.es\/de\/#\/schema\/logo\/image\/","url":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","contentUrl":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","width":200,"height":58,"caption":"[wpseo_titles]company_Nombre"},"image":{"@id":"https:\/\/oftalmedic.es\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OftalmedicSalva\/","https:\/\/x.com\/OftalmedicSalva","https:\/\/www.instagram.com\/oftalmedic_salva","https:\/\/www.youtube.com\/channel\/UCWrAdUQk6ZmrfVUqBwX0cug","https:\/\/www.linkedin.com\/company\/oftalmedic-clnica-salv\/"]}]}},"_links":{"self":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/10887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/comments?post=10887"}],"version-history":[{"count":0,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/10887\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/11308"}],"wp:attachment":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/media?parent=10887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}