{"id":11880,"date":"2025-07-09T06:08:09","date_gmt":"2025-07-09T06:08:09","guid":{"rendered":"https:\/\/oftalmedic.rwdesarrollos.es\/principales-afecciones-visuales\/kindheit\/"},"modified":"2025-07-09T06:08:11","modified_gmt":"2025-07-09T06:08:11","slug":"kindheit","status":"publish","type":"page","link":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/","title":{"rendered":"Kindheit"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;80&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#c9d6e8&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;mountains&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][split_line_heading animation_type=&#8220;default&#8220;]\n<h1>Schwere Sehbehinderungen im Kindesalter<\/h1>\n[\/split_line_heading][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;20&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; class=&#8220;infancia&#8220; id=&#8220;sub-menu-afecciones&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#c9d6e8&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;mountains&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][page_submenu alignment=&#8220;center&#8220; bg_color=&#8220;&#8220;][page_link link_url=&#8220;\/principales-afecciones-visuales\/&#8220; title=&#8220;ALLE ANZEIGEN&#8220; id=&#8220;1614245146710-7&#8243; tab_id=&#8220;1614245146712-5&#8243;] [\/page_link][page_link link_url=&#8220;\/principales-afecciones-visuales\/infancia&#8220; title=&#8220;Kindheit&#8220; id=&#8220;1614245146801-4&#8243; tab_id=&#8220;1614245146803-6&#8243;] [\/page_link][page_link link_url=&#8220;\/principales-afecciones-visuales\/adolescencia&#8220; title=&#8220;Adoleszenz&#8220; id=&#8220;1614245146843-0&#8243; tab_id=&#8220;1614245146844-3&#8243;] [\/page_link][page_link link_url=&#8220;\/principales-afecciones-visuales\/edad-adulta&#8220; title=&#8220;Erwachsensein&#8220; id=&#8220;1614245146873-4&#8243; tab_id=&#8220;1614245146875-10&#8243;] [\/page_link][page_link link_url=&#8220;\/principales-afecciones-visuales\/tercera-edad\/&#8220; title=&#8220;\u00c4ltlich&#8220; id=&#8220;1614245146920-2&#8243; tab_id=&#8220;1614245146923-2&#8243;] [\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;30&#8243; bottom_padding=&#8220;80&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_row_inner equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][image_with_animation image_url=&#8220;4332&#8243; animation=&#8220;Fade In&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column_inner][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/2&#8243; tablet_width_inherit=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][vc_column_text]\n<h2>Kindheit<\/h2>\n<p>Bei Kindern ist es ratsam, ab einem Alter von 3 bis 4 Jahren eine erste umfassende augen\u00e4rztliche Untersuchung durchzuf\u00fchren, um noch latente Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen, und diese Untersuchung jedes Jahr zu wiederholen.<\/p>\n<p>Wenn es eine famili\u00e4re Vorgeschichte gibt oder bereits Symptome aufgetreten sind, wird empfohlen, vor diesem Alter einen Augenarzt aufzusuchen.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][toggles style=&#8220;minimal&#8220;][toggle color=&#8220;Accent-Color&#8220; title=&#8220;ASTIGMATISMUS&#8220;][vc_column_text]Astigmatismus ist ein Brechungsfehler, der zu verschwommenem und verzerrtem Sehen f\u00fchrt, sowohl im Nah- als auch im Fernsehen, und der sich manifestiert, wenn Bilder auf mehrere Punkte auf der Netzhaut fokussiert werden. Im Gegensatz dazu fokussieren sich die Bilder bei emmetropen (nicht verschreibungspflichtigen) Augen auf einen einzigen Punkt auf der Netzhaut. <\/p>\n<p>Menschen, die an Astigmatismus leiden, zeichnen sich durch eine ver\u00e4nderte Hornhautkr\u00fcmmung aus, d. h. ihre Hornhaut ist nicht symmetrisch, sondern unregelm\u00e4\u00dfig gekr\u00fcmmt.<\/p>\n<p>Diese Sehanomalie tritt nicht immer isoliert auf, da sie h\u00e4ufig mit Myopie oder Hyperopie einhergeht.<\/p>\n<p>Wie Myopie und Hyperopie kann auch Astigmatismus genetisch bedingt sein. Er kann auch nach einem Trauma, einer Verletzung oder Krankheit oder als Folge einer Augenoperation auftreten. <\/p>\n<p>Astigmatismus ist das dritth\u00e4ufigste Sehproblem der Spanier (nach Kurzsichtigkeit und Alterssichtigkeit), denn mehr als ein Viertel der Bev\u00f6lkerung leidet darunter.<u><\/u><\/p>\n<p>Das Hauptsymptom des Astigmatismus ist eine <strong>verschwommene und verzerrteSicht auf nahe und ferne Objekte<\/strong> sowie Schwierigkeiten bei der Wahrnehmung feiner Details in allen Entfernungen.<\/p>\n<p>Wenn Astigmatismus in Verbindung mit Hyperopie auftritt, kommt es h\u00e4ufig zu Symptomen wie Erm\u00fcdung des Auges, R\u00f6tung, Jucken und Stechen der Augen, Schwindel oder gelegentlichen Kopfschmerzen, die auf die \u00dcberanstrengung des Auges bei der Bildsch\u00e4rfe zur\u00fcckzuf\u00fchren sind.<\/p>\n<p>Die Symptome, die der Patient wahrnehmen kann, sind je nach Alter, Art des Astigmatismus oder Sehst\u00e4rke unterschiedlich. In leichten F\u00e4llen ist es jedoch m\u00f6glich, dass keine Anzeichen f\u00fcr Astigmatismus festgestellt werden.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;\/cirugia-refractiva\/astigmatismo\/&#8220; text=&#8220;MEHR \u00dcBER ASTIGMATISMUS&#8220;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;Kongenitaler (angeborener) Katarakt&#8220;][vc_column_text]Der angeborene Graue Star ist eine Katarakt, an der das Kind zum Zeitpunkt der Geburt leidet und die je nach Grad der Tr\u00fcbung der Linse das Sehverm\u00f6gen erschweren oder ernsthaft beeintr\u00e4chtigen kann.<\/p>\n<p>In der Regel ist das Altern die Hauptursache f\u00fcr die Entstehung des Grauen Stars, da die Linse im Laufe der Jahre undurchsichtig wird. Es ist jedoch m\u00f6glich, dass ein Kind diese Pathologie auch bei der Geburt hat. <\/p>\n<p>Im Gegensatz zu Erwachsenen wird diese Art des Grauen Stars nicht durch Ver\u00e4nderungen des Sehverm\u00f6gens diagnostiziert, sondern durch einen sichtbaren wei\u00dflichen oder gr\u00e4ulichen Fleck in der Pupille. Andere Symptome des angeborenen Grauen Stars, die beim Kind als Folge einer Sehschw\u00e4che auftreten k\u00f6nnen, sind die unwillk\u00fcrliche und schnelle Bewegung der Augen (<strong>Nystagmus<\/strong>) oder die Augenabweichung (<strong>Strabismus<\/strong>). <\/p>\n<p>Wenn es sich um einen leichten angeborenen Katarakt handelt, manifestieren sich diese Symptome m\u00f6glicherweise nicht deutlich genug. Daher ist es wichtig, das Kind nach der Geburt einer ersten augen\u00e4rztlichen Untersuchung zu unterziehen, um sie sowie andere angeborene Sehst\u00f6rungen auszuschlie\u00dfen. <\/p>\n<p>Das Vorhandensein (in einem oder beiden Augen) ist eine seltene Situation, die in der Regel mit erblichen Faktoren verbunden ist, obwohl es auch andere Ursachen geben kann, wie z. B. damit verbundene Augenpathologien oder genetische Erkrankungen.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/catarata-congenita\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;\/cataratas&#8220; text=&#8220;BEHANDLUNG DES GRAUEN STARS&#8220; margin_right=&#8220;10&#8243;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;Bindehautentz\u00fcndung&#8220;][vc_column_text]Konjunktivitis ist eine Entz\u00fcndung der Bindehaut, einer durchsichtigen Membran, die die Sklera (wei\u00dfer Teil des Auges) auskleidet und kleine Blutgef\u00e4\u00dfe enth\u00e4lt. Wenn sich diese Gef\u00e4\u00dfe entz\u00fcnden, wird das Auge rot.  Es kann bei Erwachsenen und Kindern auftreten und entwickelt sich in der Regel g\u00fcnstig, es sei denn, es wird nicht richtig behandelt.<\/p>\n<p><strong>Eine Bindehautentz\u00fcndung<\/strong> kann durch eine bakterielle oder virale Infektion, eine allergische Reaktion aufgrund der Exposition gegen\u00fcber einem Wirkstoff <strong>(Allergene),<\/strong> der bei manchen Menschen eine \u00dcberempfindlichkeit hervorruft, oder eine Reizung des Augenlidrandes <strong>(Blepharitis)<\/strong> als Folge der Verwendung von Kosmetika oder des Kontakts mit reizenden Substanzen in der Umwelt verursacht werden. Jede dieser Ursachen f\u00fchrt zu verschiedenen Arten von Konjunktivitis: <strong>infekti\u00f6se Konjunktivitis, allergische Konjunktivitis, irritative Konjunktivitis.<\/strong> <\/p>\n<p>Die Symptome er Bindehautentz\u00fcndung sind sehr sichtbar und charakteristisch, wie Augenr\u00f6tung, Juckreiz (vorherrschend bei allergischer Bindehautentz\u00fcndung), Tr\u00e4nenfluss, Sekret und verklebte Augenlider (insbesondere bei bakterieller Bindehautentz\u00fcndung). Wenn eine Bindehautentz\u00fcndung mit Komplikationen auftritt, kann sie in geringerem Ma\u00dfe ein Fremdk\u00f6rpergef\u00fchl im Auge, eine gr\u00f6\u00dfere Lichtempfindlichkeit und eine erhebliche Entz\u00fcndung der Augenlider hervorrufen.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/conjuntivitis\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;FARBENBLINDHEIT&#8220;][vc_column_text]Es handelt sich um eine chromatische Sehst\u00f6rung, die genetisch \u00fcbertragen wird (sie ist mit dem X-Chromosom verbunden) und aus Schwierigkeiten besteht, bestimmte Farben zu unterscheiden. Diese Dysfunktion ist mit den <strong>Zapfen<\/strong> verbunden, einer Art von Photorezeptorzellen im menschlichen Auge, die f\u00fcr die Erkennung von Farben verantwortlich sind und sich in der oberfl\u00e4chlichsten Schicht der Netzhaut befinden. <\/p>\n<p>Farbenblindheit ist bei M\u00e4nnern h\u00e4ufiger (8 % bei Jungen und 0,5 % bei M\u00e4dchen). Die klassische Form der Farbenblindheit ist der Wechsel zwischen Rot und Gr\u00fcn, obwohl es unterschiedliche Grade der Farbenblindheit gibt. F\u00fcr Farbenblindheit gibt es keine Behandlung, aber es ist wichtig, sie bei Kindern zu erkennen, da sie ihre pers\u00f6nliche Entwicklung sowie ihren Lernprozess beeinflussen kann.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/daltonismo\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;STRABISMUS&#8220;][vc_column_text]Es handelt sich um einen Sehfehler, der in der Abweichung eines oder beider Augen in einer der Blickpositionen besteht, die auf die mangelnde Koordination zwischen den Augenmuskeln zur\u00fcckzuf\u00fchren ist. Dies f\u00fchrt zum Verlust der Parallelit\u00e4t zwischen den beiden Augen und zu falschem <strong>binokularen Sehen<\/strong> , was sich auf die F\u00e4higkeit auswirkt, im Relief zu sehen, Entfernungen zu berechnen und in 3D zu sehen. <\/p>\n<p>Kleine intermittierende Abweichungen k\u00f6nnen vor 6 Monaten auftreten, ohne dass sie notwendigerweise mit Problemen verbunden sind. Dieses funktionelle Schielen bei Neugeborenen wird als <strong>angeborenes Schielen<\/strong> bezeichnet. Sie sollten jedoch den Augenarzt aufsuchen, wenn es sich um eine dauerhafte Abweichung handelt. Es ist zu beachten, dass die Abnahme des Sehverm\u00f6gens des abweichenden Auges dauerhaft und irreversibel werden kann, wenn das Schielen nicht fr\u00fchzeitig korrigiert wird, dh etwa vor dem 7. bis 8. Lebensjahr.   <\/p>\n<p><strong> <\/strong><strong>Amblyopie oder Tr\u00e4gheit ist<\/strong> die schwerwiegendste Folge des Schielens und die h\u00e4ufigste Ursache f\u00fcr einseitigen Sehverlust (Sehkraft auf nur einem Auge) bei Kindern und Jugendlichen. Das Kind, das an einem tr\u00e4gen Auge leidet, benutzt ein Auge weniger als das andere, was \u201efaul\u201c wird. <\/p>\n<p>Schielen kann nach verschiedenen Kriterien klassifiziert werden, wie z.B. der Richtung der Abweichung (konvergent, divergent und vertikal), der Persistenz \u00fcber die Zeit (vor\u00fcbergehend und dauerhaft) und der Dominanz oder Nichtdominanz eines Auges. In diesem Fall kann Schielen abwechselnd auftreten, das hei\u00dft, manchmal schaut das Kind mit einem Auge (dominantes Auge) und weicht vom anderen ab, und manchmal macht es es umgekehrt. Das dominante Auge kann sich abwechseln oder immer gleich sein.  <\/p>\n<p>Die Entstehung des Schielens h\u00e4ngt haupts\u00e4chlich mit Ver\u00e4nderungen in der Funktion der Augenmuskeln, Sehunterschieden zwischen den beiden Augen aufgrund von damit verbundenen Brechungsfehlern und Traumata zusammen, die Druck auf das Auge aus\u00fcben.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/estrabismo\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;ANGEBORENES GLAUKOM (VON GEBURT AN)&#8220;][vc_column_text]Das angeborene Glaukom ist eine Form des Glaukoms, die nur im Kindesalter auftritt. Diese Geburtskrankheit f\u00fchrt zu einer fortschreitenden Sch\u00e4digung des Sehnervs, der f\u00fcr die \u00dcbertragung von Informationen vom Auge zum Gehirn verantwortlich ist. Als Folge dieser Sch\u00e4digung kommt es je nach Grad der Degeneration zu einem milderen oder schwereren Verlust des Sehverm\u00f6gens.  <\/p>\n<p>Der Hauptrisikofaktor f\u00fcr die Entwicklung eines Glaukoms ist ein erh\u00f6hter Augeninnendruck. Dieser Anstieg des <strong>Augeninnendrucks (IOD)<\/strong> wird durch ein Ungleichgewicht zwischen der Produktion und Ausscheidung des <strong>Kammerwassers <\/strong>(eine farblose Fl\u00fcssigkeit, die die Augenstrukturen mit Sauerstoff versorgt und n\u00e4hrt) verursacht, was die ordnungsgem\u00e4\u00dfe Funktion des Auges beeintr\u00e4chtigt. <\/p>\n<p>Das angeborene Glaukom manifestiert sich in der Regel in den ersten drei Lebensjahren, obwohl es selten ist, da es 1 von 30.000 Neugeborenen betrifft. Die typischen Symptome, die Eltern beim Kind beobachten sollten, sind, dass sie durch Licht gest\u00f6rt werden (Photophobie), ihre Augen tr\u00e4nen und dass sie diese meist geschlossen haben. <\/p>\n<p>Mit fortschreitender Krankheit \u00e4ndert sich das normale Aussehen der Augen, wenn die Transparenz der Hornhaut verloren geht und das Auge aufgrund von Dehnungen im Gewebe \u00fcberproportional vergr\u00f6\u00dfert wird.<\/p>\n<p>Um die Diagnose zu best\u00e4tigen, muss der Augenarzt das betroffene Kind eingehend untersuchen.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/glaucoma-congenito\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;\/glaucoma\/&#8220; text=&#8220;GLAUKOM&#8220; margin_right=&#8220;10&#8243;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;HYPERMETROPIA&#8220;][vc_column_text]Weitsichtigkeit ist ein Brechungsfehler, der zu einem verschwommenen und unangenehmen Sehen von Objekten in der N\u00e4he (und manchmal auch von entfernten Objekten) f\u00fchrt. Anders als bei der Kurzsichtigkeit werden die Bilder hinter der Netzhaut fokussiert und nicht direkt auf diese.<\/p>\n<p>Menschen, die an Hyperopie leiden, zeichnen sich durch Ver\u00e4nderungen der verschiedenen Strukturen des Auges aus, wie z. B. der Hornhautkr\u00fcmmung, der optischen St\u00e4rke der Augenlinse (geringe Brechkraft) oder der Gr\u00f6\u00dfe des Augapfels (k\u00fcrzer als die normale L\u00e4nge).<strong> <\/strong><\/p>\n<p>Wie bei der Kurzsichtigkeit gibt es auch bei der Weitsichtigkeit eine wichtige erbliche Komponente.<strong> <\/strong><\/p>\n<p>Das Hauptsymptom der Hyperopie ist eine <strong>schlechte Sicht in der N\u00e4he.<\/strong> Wenn die Weitsichtigkeit gering ist, sieht der Patient in der Ferne gut, obwohl die Fokussierungs- oder Akkommodationsanstrengung gr\u00f6\u00dfer ist. Dies kann zu anderen Symptomen wie Kopfschmerzen und \u00dcberanstrengung der Augen f\u00fchren. <\/p>\n<p>In vielen F\u00e4llen sind die Auswirkungen erst ab dem 40. Lebensjahr zu sp\u00fcren, wenn die Anpassungsf\u00e4higkeit nachl\u00e4sst.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/cirugia-refractiva\/hipermetropia\/&#8220; text=&#8220;MEHR \u00dcBER HIPERMETROPIE&#8220;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;MIOPIA&#8220;][vc_column_text]Myopie ist ein Brechungsfehler, der auftritt, wenn weit entfernte Objekte auf einen Punkt vor der Netzhaut projiziert werden, anstatt auf die Netzhaut. Dies f\u00fchrt zu einer verzerrten Wahrnehmung des Bildes und damit zu unscharfem und verschwommenem Sehen. <\/p>\n<p>Menschen, die an Kurzsichtigkeit leiden, zeichnen sich durch Ver\u00e4nderungen der verschiedenen Strukturen des Auges aus, wie z. B. der Hornhautkr\u00fcmmung, der optischen St\u00e4rke der Augenlinse (\u00fcberm\u00e4\u00dfige St\u00e4rke) oder der Gr\u00f6\u00dfe des Augapfels (\u00fcberm\u00e4\u00dfige L\u00e4nge).<\/p>\n<p>Myopie ist die h\u00e4ufigste Sehschw\u00e4che bei Menschen unter 45 Jahren und kann in Verbindung mit anderen Brechungsfehlern wie <a href=\"https:\/\/oftalmedic.es\/de\/cirugia-refractiva\/astigmatismo-2\/\" target=\"_blank\" rel=\"noopener\">Astigmatismus <\/a>(myopischer Astigmatismus) und Alterssichtigkeit (<a href=\"https:\/\/oftalmedic.es\/de\/presbyopie\/\" target=\"_blank\" rel=\"noopener\">Presbyopie<\/a>) oder Sehschw\u00e4che auftreten.<\/p>\n<p>Das Hauptsymptom eines Patienten mit Myopie ist, <strong>dass er schlecht in die Ferne<\/strong> und dennoch optimal in die N\u00e4he sehen kann. Andere Symptome, unter denen sie leiden k\u00f6nnen, sind visuelle M\u00fcdigkeit, Kopfschmerzen, Konzentrationsschwierigkeiten, st\u00e4ndige Trockenheit\/Juckreiz der Augen usw. <\/p>\n<p>Die Symptome der Myopie k\u00f6nnen bereits in jungen Jahren auftreten. Aus diesem Grund ist es ratsam, im Alter von 3 bis 4 Jahren eine vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um eine noch latente Sehver\u00e4nderung festzustellen oder auszuschlie\u00dfen. Besteht eine famili\u00e4re Vorbelastung oder gibt es fr\u00fchere Symptome, wird empfohlen, diese Untersuchung vor diesem Alter durchf\u00fchren zu lassen.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/cirugia-refractiva\/miopia\/&#8220; text=&#8220;MEHR \u00dcBER MYOPIE&#8220;][\/toggle][toggle color=&#8220;Default&#8220; title=&#8220;TR\u00c4GES AUGE ODER AMBLYOPIE&#8220;][vc_column_text]Tr\u00e4ges Auge oder Amblyopie tritt auf, wenn eines der beiden Augen weniger benutzt wird als das andere, weil der Patient an <strong>Schielen<\/strong> leidet oder einen gro\u00dfen Unterschied in der Verschreibung zwischen den beiden Augen hat, so dass eines der beiden als dominantes Auge fungiert.<\/p>\n<p>Die Amblyopie manifestiert sich in der Kindheit nur auf einem Auge (obwohl sie beide betreffen kann), da es in der kritischen Phase der visuellen Entwicklung an ausreichender visueller Stimulation mangelt. Diese Krankheit betrifft etwa 5% der Kinder. <\/p>\n<p>Das tr\u00e4ge Auge ist eine Pathologie, die zum richtigen Zeitpunkt (vor dem Alter von 7-8 Jahren) erkannt und behandelt werden sollte, um eine bessere Prognose f\u00fcr die Wiederherstellung des Sehverm\u00f6gens zu erhalten. Tats\u00e4chlich gewinnen Patienten, die wegen Amblyopie behandelt werden, in der Regel ihr Sehverm\u00f6gen vollst\u00e4ndig zur\u00fcck und entwickeln ihr Leben normal. <\/p>\n<p>Auf der anderen Seite, wenn dieses Problem nicht rechtzeitig erkannt wird, kann es bis ins Erwachsenenalter andauern, ohne dass die M\u00f6glichkeit besteht, das Sehverm\u00f6gen des Auges zu korrigieren, das nicht verwendet wird. Dies kann zu einem dauerhaften und irreversiblen Verlust der Sehsch\u00e4rfe f\u00fchren. <\/p>\n<p>Einige der Symptome von Kindern, die unter einem tr\u00e4gen Auge leiden und Eltern und Erzieher alarmieren sollten, sind unter anderem Kopfverdrehen, st\u00e4ndiges Blinzeln, Augenzwinkern, verschwommenes Sehen, Doppeltsehen, sich n\u00e4hernde Objekte, Augenr\u00f6tung.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/ojo-vago\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][\/toggle][toggle color=&#8220;Accent-Color&#8220; title=&#8220;PTOSIS DES INFANTILEN AUGENLIDS&#8220;][vc_column_text]Die Augenlidptosis ist das Herabh\u00e4ngen des oberen Augenlids, das das Auge teilweise oder vollst\u00e4ndig bedeckt. Diese Ver\u00e4nderung der normalen Position kann das Gesichtsfeld beeintr\u00e4chtigen und das Sehverm\u00f6gen des Patienten ernsthaft beeintr\u00e4chtigen. Wenn sie vor dem 8. Lebensjahr auftritt, wird sie als infantile Augenlidptosis bezeichnet.  <\/p>\n<p>Diese Art von <strong>Lidfehlstellung<\/strong> <strong>bei Kindern<\/strong> tritt von Geburt an auf, da sie in der Regel angeborenen Ursprungs ist und in der Regel mit einer schlechten Entwicklung des Muskels zusammenh\u00e4ngt, der f\u00fcr das Anheben des Augenlids verantwortlich ist. Im Gegenteil, bei Erwachsenen wird es in der Regel durch mehrere Ursachen (Alter, Trauma, Funktionsprobleme des Muskels usw.) erworben. <\/p>\n<p>Bei Kindern, die an einer Augenlidptose leiden, gibt es untr\u00fcgliche Anzeichen, wie z. B. das Neigen des Kopfes nach hinten, um besser sehen zu k\u00f6nnen, oder sogar das Anheben des Augenlids mit den Fingern. Im Allgemeinen ist es schwierig, die Augen offen zu halten, wenn sie t\u00e4glichen Aktivit\u00e4ten wie Lesen, Schreiben, Zeichnen usw. nachgehen.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;regular&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oftalmologia-pediatrica\/ptosis-palpebral\/&#8220; text=&#8220;KINDERAUGENHEILKUNDE&#8220; margin_right=&#8220;10&#8243;][nectar_btn size=&#8220;small&#8220; open_new_tab=&#8220;true&#8220; button_style=&#8220;see-through&#8220; button_color_2=&#8220;Accent-Color&#8220; icon_family=&#8220;none&#8220; url=&#8220;https:\/\/oftalmedic.es\/oculoplastia\/malposiciones-mas-frecuentes-en-los-parpados\/&#8220; text=&#8220;OKULOPLASTIK&#8220; margin_right=&#8220;10&#8243;][\/toggle][\/toggles][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;80&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_color=&#8220;#c9d6e8&#8243; shape_divider_position=&#8220;bottom&#8220; shape_divider_height=&#8220;100&#8243; bg_image_animation=&#8220;none&#8220; shape_type=&#8220;mountains&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220; bg_image_animation=&#8220;none&#8220;][split_line_heading animation_type=&#8220;default&#8220;] Schwere Sehbehinderungen im Kindesalter [\/split_line_heading][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; top_padding=&#8220;20&#8243; text_color=&#8220;dark&#8220; text_align=&#8220;center&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; class=&#8220;infancia&#8220; id=&#8220;sub-menu-afecciones&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":10400,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11880","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0<\/title>\n<meta name=\"description\" content=\"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0\" \/>\n<meta property=\"og:description\" content=\"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Oftalmedic Salv\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OftalmedicSalva\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-09T06:08:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OftalmedicSalva\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"17\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/kindheit\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/kindheit\\\/\",\"name\":\"Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#website\"},\"datePublished\":\"2025-07-09T06:08:09+00:00\",\"dateModified\":\"2025-07-09T06:08:11+00:00\",\"description\":\"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/kindheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/kindheit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/kindheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wichtigste visuelle Bedingungen\",\"item\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/principales-afecciones-visuales\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kindheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/\",\"name\":\"Oftalmedic Salv\u00e1\",\"description\":\"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#organization\",\"name\":\"[wpseo_titles]company_Nombre\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"contentUrl\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"width\":200,\"height\":58,\"caption\":\"[wpseo_titles]company_Nombre\"},\"image\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OftalmedicSalva\\\/\",\"https:\\\/\\\/x.com\\\/OftalmedicSalva\",\"https:\\\/\\\/www.instagram.com\\\/oftalmedic_salva\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWrAdUQk6ZmrfVUqBwX0cug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/oftalmedic-clnica-salv\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0","description":"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/","og_locale":"de_DE","og_type":"article","og_title":"Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0","og_description":"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.","og_url":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/","og_site_name":"Oftalmedic Salv\u00e1","article_publisher":"https:\/\/www.facebook.com\/OftalmedicSalva\/","article_modified_time":"2025-07-09T06:08:11+00:00","twitter_card":"summary_large_image","twitter_site":"@OftalmedicSalva","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"17\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/","url":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/","name":"Sehst\u00f6rungen im Kindesalter | Oftalmedic Salv\u00e0","isPartOf":{"@id":"https:\/\/oftalmedic.es\/de\/#website"},"datePublished":"2025-07-09T06:08:09+00:00","dateModified":"2025-07-09T06:08:11+00:00","description":"Im Kindesalter ist es ratsam, eine erste vollst\u00e4ndige augen\u00e4rztliche Untersuchung durchf\u00fchren zu lassen, um Sehst\u00f6rungen zu erkennen oder auszuschlie\u00dfen.","breadcrumb":{"@id":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/kindheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oftalmedic.es\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Wichtigste visuelle Bedingungen","item":"https:\/\/oftalmedic.es\/de\/principales-afecciones-visuales\/"},{"@type":"ListItem","position":3,"name":"Kindheit"}]},{"@type":"WebSite","@id":"https:\/\/oftalmedic.es\/de\/#website","url":"https:\/\/oftalmedic.es\/de\/","name":"Oftalmedic Salv\u00e1","description":"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.","publisher":{"@id":"https:\/\/oftalmedic.es\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oftalmedic.es\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/oftalmedic.es\/de\/#organization","name":"[wpseo_titles]company_Nombre","url":"https:\/\/oftalmedic.es\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oftalmedic.es\/de\/#\/schema\/logo\/image\/","url":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","contentUrl":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","width":200,"height":58,"caption":"[wpseo_titles]company_Nombre"},"image":{"@id":"https:\/\/oftalmedic.es\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OftalmedicSalva\/","https:\/\/x.com\/OftalmedicSalva","https:\/\/www.instagram.com\/oftalmedic_salva","https:\/\/www.youtube.com\/channel\/UCWrAdUQk6ZmrfVUqBwX0cug","https:\/\/www.linkedin.com\/company\/oftalmedic-clnica-salv\/"]}]}},"_links":{"self":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/11880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/comments?post=11880"}],"version-history":[{"count":0,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/11880\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/pages\/10400"}],"wp:attachment":[{"href":"https:\/\/oftalmedic.es\/de\/wp-json\/wp\/v2\/media?parent=11880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}