{"id":11524,"date":"2025-07-07T06:16:11","date_gmt":"2025-07-07T06:16:11","guid":{"rendered":"https:\/\/oftalmedic.rwdesarrollos.es\/team\/dr-jorge-garcia-garcia\/"},"modified":"2025-07-07T06:16:11","modified_gmt":"2025-07-07T06:16:11","slug":"dr-jorge-garcia-garcia","status":"publish","type":"page","link":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/","title":{"rendered":"Dr. Jorge Garc\u00eda Garc\u00eda"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;4890&#8243; animation=&#8221;Fade In&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h1>Dr. Jorge Garc\u00eda Garc\u00eda<\/h1>\n<p>Number of colleges: 073705581[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;4&#8243; divider_color=&#8221;default&#8221; animate=&#8221;yes&#8221; custom_height=&#8221;30&#8243;][vc_column_text]\n<h5>Qualifications and training<\/h5>\n<ul>\n<li>Degree in Medicine and Surgery from the University of Oviedo.<\/li>\n<li>Specialist in Ophthalmology via MIR by the University Hospital of Salamanca.<\/li>\n<li>D. studies in the Program &#8220;Neurosciences: Morphofunctional Organization of the Nervous System&#8221; of the University of Salamanca.<\/li>\n<\/ul>\n<h5>Career path<\/h5>\n<ul>\n<li>Ophthalmologist (Anterior Segment) at Oftalmedic Salv\u00e0.<\/li>\n<li>Teaching commission at the Strabology Department of the Hospital Infantil Universitario Ni\u00f1o Jes\u00fas (Madrid).<\/li>\n<li>Ophthalmologist at the General Hospital of Mallorca.<\/li>\n<li>Ophthalmologist at the Hospital Universitari Son Ll\u00e0tzer.<\/li>\n<\/ul>\n<h5>Languages<\/h5>\n<p>Spanish, English, French, Italian.[\/vc_column_text][nectar_btn size=&#8221;small&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; icon_family=&#8221;none&#8221; url=&#8221;\/equipo\/&#8221; text=&#8221;MEDICAL TEAM&#8221; margin_top=&#8221;30px&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;left-right&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1642765767749{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #f8f8f8 !important;}&#8221;]\n<h5><strong>Specialist in<\/strong><\/h5>\n<ul>\n<li class=\"m_-3021878908583798202MsoListParagraph\"><a href=\"https:\/\/oftalmedic.es\/en\/oftalmologia-general\/\" target=\"_blank\" rel=\"noopener\">General Ophthalmology<\/a><u><\/u><u><\/u><\/li>\n<li><a href=\"https:\/\/oftalmedic.es\/en\/unidad-de-retina\/\" target=\"_blank\" rel=\"noopener\">Medical retina<\/a><\/li>\n<li class=\"m_-3021878908583798202MsoListParagraph\"><a href=\"https:\/\/oftalmedic.es\/en\/cataratas\/\" target=\"_blank\" rel=\"noopener\">Cataract treatment<\/a><\/li>\n<\/ul>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;30&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":12433,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-11524","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca<\/title>\n<meta name=\"description\" content=\"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca\" \/>\n<meta property=\"og:description\" content=\"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Oftalmedic Salv\u00e1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/OftalmedicSalva\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@OftalmedicSalva\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/equipo\\\/dr-jorge-garcia-garcia\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/equipo\\\/dr-jorge-garcia-garcia\\\/\",\"name\":\"Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#website\"},\"datePublished\":\"2025-07-07T06:16:11+00:00\",\"description\":\"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/equipo\\\/dr-jorge-garcia-garcia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/oftalmedic.es\\\/en\\\/equipo\\\/dr-jorge-garcia-garcia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/equipo\\\/dr-jorge-garcia-garcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/oftalmedic-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Jorge Garc\u00eda Garc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/\",\"name\":\"Oftalmedic Salv\u00e1\",\"description\":\"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.\",\"publisher\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#organization\",\"name\":\"[wpseo_titles]company_Nombre\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"contentUrl\":\"https:\\\/\\\/oftalmedic.es\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/logo-oftalmedic.png\",\"width\":200,\"height\":58,\"caption\":\"[wpseo_titles]company_Nombre\"},\"image\":{\"@id\":\"https:\\\/\\\/oftalmedic.es\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OftalmedicSalva\\\/\",\"https:\\\/\\\/x.com\\\/OftalmedicSalva\",\"https:\\\/\\\/www.instagram.com\\\/oftalmedic_salva\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWrAdUQk6ZmrfVUqBwX0cug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/oftalmedic-clnica-salv\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca","description":"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/","og_locale":"en_US","og_type":"article","og_title":"Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca","og_description":"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.","og_url":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/","og_site_name":"Oftalmedic Salv\u00e1","article_publisher":"https:\/\/www.facebook.com\/OftalmedicSalva\/","twitter_card":"summary_large_image","twitter_site":"@OftalmedicSalva","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/","url":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/","name":"Dr Jorge Garc\u00eda: Cataract Specialist: Ophthalmologist Palma de Mallorca","isPartOf":{"@id":"https:\/\/oftalmedic.es\/en\/#website"},"datePublished":"2025-07-07T06:16:11+00:00","description":"Dr. Jorge Garc\u00eda Garc\u00eda. Ophthalmologist in Palma specialized in the treatment of cataracts and general ophthalmology in Oftalmedic Salv\u00e0.","breadcrumb":{"@id":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/oftalmedic.es\/en\/equipo\/dr-jorge-garcia-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/oftalmedic.es\/en\/oftalmedic-2\/"},{"@type":"ListItem","position":2,"name":"Dr. Jorge Garc\u00eda Garc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/oftalmedic.es\/en\/#website","url":"https:\/\/oftalmedic.es\/en\/","name":"Oftalmedic Salv\u00e1","description":"Red de cl\u00ednicas oftalmol\u00f3gicas de referencia en Baleares. Pionera en tecnolog\u00eda l\u00e1ser para cirug\u00eda de cataratas y correcci\u00f3n de la miop\u00eda, hipermetrop\u00eda, astigmatismo y presbicia o vista cansada.","publisher":{"@id":"https:\/\/oftalmedic.es\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oftalmedic.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oftalmedic.es\/en\/#organization","name":"[wpseo_titles]company_Nombre","url":"https:\/\/oftalmedic.es\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oftalmedic.es\/en\/#\/schema\/logo\/image\/","url":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","contentUrl":"https:\/\/oftalmedic.es\/wp-content\/uploads\/2018\/06\/logo-oftalmedic.png","width":200,"height":58,"caption":"[wpseo_titles]company_Nombre"},"image":{"@id":"https:\/\/oftalmedic.es\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OftalmedicSalva\/","https:\/\/x.com\/OftalmedicSalva","https:\/\/www.instagram.com\/oftalmedic_salva","https:\/\/www.youtube.com\/channel\/UCWrAdUQk6ZmrfVUqBwX0cug","https:\/\/www.linkedin.com\/company\/oftalmedic-clnica-salv\/"]}]}},"_links":{"self":[{"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/pages\/11524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/comments?post=11524"}],"version-history":[{"count":0,"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/pages\/11524\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/pages\/12433"}],"wp:attachment":[{"href":"https:\/\/oftalmedic.es\/en\/wp-json\/wp\/v2\/media?parent=11524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}